{"id":1156,"date":"2022-08-21T01:10:31","date_gmt":"2022-08-21T01:10:31","guid":{"rendered":"https:\/\/kb.shahbandr.com\/?post_type=kb&#038;p=1156"},"modified":"2024-02-21T09:40:32","modified_gmt":"2024-02-21T09:40:32","slug":"documentation-multilingual-for-translate","status":"publish","type":"kb","link":"https:\/\/kb-legacy.shahbandr.com\/en\/kb\/documentation-multilingual-for-translate\/","title":{"rendered":"\u0634\u0631\u062d \u0627\u0636\u0627\u0641\u0629 Multilingual \u0644\u062a\u0631\u062c\u0645\u0629 \u0627\u0644\u0645\u062a\u062c\u0631"},"content":{"rendered":"<span class=\"mkb-shortcode-container\">\t\t<div class=\"mkb-tip\">\n\t\t\t<div class=\"mkb-tip__icon\">\n\t\t\t\t<i class=\"fa fa-lightbulb-o fa-lg\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"mkb-tip__content\">\n\t\t\t\t\u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0645\u0642\u0627\u0644\u0629 \u0633\u0648\u0641 \u0646\u0631\u0649 \u0643\u064a\u0641\u064a\u0629 \u062a\u0641\u0639\u064a\u0644 \u0627\u0636\u0627\u0641\u0629 Multilingual \u0644\u062a\u0631\u062c\u0645\u0629 \u0627\u0644\u0645\u062a\u062c\u0631\t\t\t<\/div>\n\t\t<\/div>\n\t<\/span>\n<span class=\"mkb-shortcode-container\">\t\t<div class=\"mkb-anchor mkb-clearfix mkb-back-to-top-inline\">\n\t\t\t<h3 class=\"mkb-anchor__title\">\u062a\u0641\u0639\u064a\u0644 \u0627\u0644\u0627\u0636\u0627\u0641\u0629\u00a0<\/h3>\n\t\t\t\t\t\t\t<a href=\"#\" class=\"mkb-back-to-top\" title=\"\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\">\n\t\t\t\t\t\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\t\t\t\t\t\t\t\t\t\t\t<i class=\"mkb-back-to-top-icon fa back_to_top_icon\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/span>\n<p>\u0645\u0646 \u0627\u0644\u0627\u0636\u0627\u0641\u0627\u062a \u0646\u0642\u0648\u0645 \u0628\u062a\u0641\u0639\u064a\u0644 Multilingual<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1157 aligncenter\" src=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi1.png\" alt=\"\" width=\"1366\" height=\"625\" srcset=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi1.png 1366w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi1-300x137.png 300w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi1-1024x469.png 1024w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi1-768x351.png 768w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi1-18x8.png 18w\" sizes=\"auto, (max-width: 1366px) 100vw, 1366px\" \/><\/p>\n<span class=\"mkb-shortcode-container\">\t\t<div class=\"mkb-anchor mkb-clearfix mkb-back-to-top-inline\">\n\t\t\t<h3 class=\"mkb-anchor__title\">\u0627\u0636\u0627\u0641\u0629 \u0644\u063a\u0629 \u062c\u062f\u064a\u062f\u0629<\/h3>\n\t\t\t\t\t\t\t<a href=\"#\" class=\"mkb-back-to-top\" title=\"\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\">\n\t\t\t\t\t\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\t\t\t\t\t\t\t\t\t\t\t<i class=\"mkb-back-to-top-icon fa back_to_top_icon\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/span>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1158 aligncenter\" src=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi2.png\" alt=\"\" width=\"1349\" height=\"625\" srcset=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi2.png 1349w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi2-300x139.png 300w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi2-1024x474.png 1024w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi2-768x356.png 768w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi2-18x8.png 18w\" sizes=\"auto, (max-width: 1349px) 100vw, 1349px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1159 aligncenter\" src=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi3.png\" alt=\"\" width=\"1366\" height=\"1261\" srcset=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi3.png 1366w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi3-300x277.png 300w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi3-1024x945.png 1024w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi3-768x709.png 768w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi3-13x12.png 13w\" sizes=\"auto, (max-width: 1366px) 100vw, 1366px\" \/><\/p>\n<span class=\"mkb-shortcode-container\">\t\t<div class=\"mkb-anchor mkb-clearfix mkb-back-to-top-inline\">\n\t\t\t<h3 class=\"mkb-anchor__title\">\u062a\u0631\u062c\u0645\u0629 \u0627\u0644\u0645\u062d\u062a\u0648\u064a\u00a0<\/h3>\n\t\t\t\t\t\t\t<a href=\"#\" class=\"mkb-back-to-top\" title=\"\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\">\n\t\t\t\t\t\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\t\t\t\t\t\t\t\t\t\t\t<i class=\"mkb-back-to-top-icon fa back_to_top_icon\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/span>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1160 aligncenter\" src=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi4.png\" alt=\"\" width=\"1349\" height=\"625\" srcset=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi4.png 1349w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi4-300x139.png 300w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi4-1024x474.png 1024w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi4-768x356.png 768w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi4-18x8.png 18w\" sizes=\"auto, (max-width: 1349px) 100vw, 1349px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1161 aligncenter\" src=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi5.png\" alt=\"\" width=\"1349\" height=\"625\" srcset=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi5.png 1349w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi5-300x139.png 300w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi5-1024x474.png 1024w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi5-768x356.png 768w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi5-18x8.png 18w\" sizes=\"auto, (max-width: 1349px) 100vw, 1349px\" \/><\/p>\n<span class=\"mkb-shortcode-container\">\t\t<div class=\"mkb-anchor mkb-clearfix mkb-back-to-top-inline\">\n\t\t\t<h3 class=\"mkb-anchor__title\">\u0627\u0636\u0627\u0641\u0629 \u062a\u063a\u064a\u0631 \u0627\u0644\u0644\u063a\u0629 \u0641\u064a \u0627\u0644\u0642\u0627\u0626\u0645\u0629<\/h3>\n\t\t\t\t\t\t\t<a href=\"#\" class=\"mkb-back-to-top\" title=\"\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\">\n\t\t\t\t\t\u0627\u0644\u0649 \u0627\u0644\u0627\u0639\u0644\u0649\t\t\t\t\t\t\t\t\t\t\t<i class=\"mkb-back-to-top-icon fa back_to_top_icon\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/span>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1162 aligncenter\" src=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi6.png\" alt=\"\" width=\"1366\" height=\"625\" srcset=\"https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi6.png 1366w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi6-300x137.png 300w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi6-1024x469.png 1024w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi6-768x351.png 768w, https:\/\/kb-legacy.shahbandr.com\/wp-content\/uploads\/2022\/08\/multi6-18x8.png 18w\" sizes=\"auto, (max-width: 1366px) 100vw, 1366px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>\u0645\u0646 \u0627\u0644\u0627\u0636\u0627\u0641\u0627\u062a \u0646\u0642\u0648\u0645 \u0628\u062a\u0641\u0639\u064a\u0644 Multilingual<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"kbtopic":[37,38],"kbtag":[],"class_list":["post-1156","kb","type-kb","status-publish","hentry","kbtopic-store-management","kbtopic-increase-sales"],"_links":{"self":[{"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/kb\/1156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/kb"}],"about":[{"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/types\/kb"}],"author":[{"embeddable":true,"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/comments?post=1156"}],"version-history":[{"count":1,"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/kb\/1156\/revisions"}],"predecessor-version":[{"id":1163,"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/kb\/1156\/revisions\/1163"}],"wp:attachment":[{"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/media?parent=1156"}],"wp:term":[{"taxonomy":"kbtopic","embeddable":true,"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/kbtopic?post=1156"},{"taxonomy":"kbtag","embeddable":true,"href":"https:\/\/kb-legacy.shahbandr.com\/en\/wp-json\/wp\/v2\/kbtag?post=1156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}